{"id":3737,"date":"2021-06-09T17:13:21","date_gmt":"2021-06-09T17:13:21","guid":{"rendered":"http:\/\/malpaisediciones.com\/sitio\/?post_type=portfolio&#038;p=3737"},"modified":"2025-07-08T13:57:32","modified_gmt":"2025-07-08T18:57:32","slug":"la-libertad-tiene-otro-nombre-antologia-de-la-poesia-politica-y-social-en-mexico","status":"publish","type":"portfolio","link":"http:\/\/malpaisediciones.com\/sitio\/portfolio\/la-libertad-tiene-otro-nombre-antologia-de-la-poesia-politica-y-social-en-mexico\/","title":{"rendered":"La libertad tiene otro nombre: Antolog\u00eda de la poes\u00eda  pol\u00edtica y social en M\u00e9xico"},"content":{"rendered":"<p><strong>Iv\u00e1n Cruz Osorio (Compilador e investigador)<\/strong><\/p>\n<p>\u201cLa libertad tiene otro nombre: Antolog\u00eda de la poes\u00eda pol\u00edtica y social en M\u00e9xico\u201d a diferencia de elaborar un trabajo antol\u00f3gico que aspira a construir un canon, un establishment, una \u00e9lite, el presente trabajo busca presentar la lucha por un pa\u00eds m\u00e1s justo, autocr\u00edtico, con mayores libertades e igualdad que las y los poetas dejaron plasmado en estos poemas y en su labor como guerrilleros, militantes y\/o activistas sociales. Es decir, esta es una antolog\u00eda de autores que dejaron la piel en las alambradas, que pelearon codo a codo en la Revoluci\u00f3n Mexicana, en movimientos obrero, campesino, estudiantil y por garant\u00edas individuales.<\/p>\n<p>Coeditado con la Secretaria de Educaci\u00f3n P\u00fablica, parte de la colecci\u00f3n Ediciones Normalismo Extraordinario<\/p>\n<p>432 pp \/ 14 x 28 cm<\/p>\n<p><strong>ISBN: 978-607-9064-44-0<\/strong><\/p>\n<p><a class=\"btnComprar\" href=\"https:\/\/malpaisediciones.com\/sitio\/producto\/la-libertad-tiene-otro-nombre-antologia-de-la-poesia-politica-y-social-en-mexico\/\">Comprar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iv\u00e1n Cruz Osorio (Compilador e investigador) \u201cLa libertad tiene otro nombre: Antolog\u00eda de la poes\u00eda pol\u00edtica y social en M\u00e9xico\u201d a diferencia de elaborar un trabajo antol\u00f3gico que aspira a construir un canon, un establishment, una \u00e9lite, el presente trabajo busca presentar la lucha por un pa\u00eds m\u00e1s justo, autocr\u00edtico, con mayores libertades e igualdad&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3741,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[50],"class_list":["post-3737","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_category-poesia"],"acf":[],"_links":{"self":[{"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/portfolio\/3737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/comments?post=3737"}],"version-history":[{"count":5,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/portfolio\/3737\/revisions"}],"predecessor-version":[{"id":4182,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/portfolio\/3737\/revisions\/4182"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/media\/3741"}],"wp:attachment":[{"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/media?parent=3737"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"http:\/\/malpaisediciones.com\/sitio\/wp-json\/wp\/v2\/portfolio_category?post=3737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}